{"id":5987,"date":"2017-05-07T17:14:00","date_gmt":"2017-05-07T21:14:00","guid":{"rendered":"https:\/\/nelidesign.com\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/"},"modified":"2018-09-29T13:58:34","modified_gmt":"2018-09-29T17:58:34","slug":"comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5","status":"publish","type":"post","link":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/","title":{"rendered":"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5"},"content":{"rendered":"<p>Vous souvenez-vous de la <a href=\"https:\/\/nelidesign.com\/one-room-challenge-craft-room-week-1\/\" target=\"_blank\" rel=\"noopener\">premi\u00e8re semaine<\/a>\u00a0du\u00a0One Room Challenge? Un de mes objectifs \u00e9tait d'installer un panneau trou\u00e9 pour cacher ce tuyau.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" fetchpriority=\"high\" class=\"aligncenter wp-image-3869 size-full\" src=\"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Craft-Room-05.FR_.jpg\" alt=\"Cacher un tuyau dans salle de bricolage avec panneau trou\u00e9 | Hide a pipe | pegboard in craftroom | how to hang a pegboard | DIY | Hooks on pegboards\" width=\"750\" height=\"663\" srcset=\"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Craft-Room-05.FR_.jpg 750w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Craft-Room-05.FR_-250x221.jpg 250w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Craft-Room-05.FR_-550x486.jpg 550w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Craft-Room-05.FR_-204x180.jpg 204w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Craft-Room-05.FR_-339x300.jpg 339w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Craft-Room-05.FR_-566x500.jpg 566w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Eh bien, je l'ai fait (je veux dire, <em>nous<\/em> l'avons fait parce que je n'aurais pas pu le faire seul! Merci ch\u00e9ri \ud83d\ude0a)<\/p>\n<p>Pour le <a href=\"http:\/\/www.callingithome.com\/blog\/2017\/5\/one-room-challenge-guest-participants-week-5\" target=\"_blank\" rel=\"noopener\">One Room Challenge<\/a>, de\u00a0<a href=\"http:\/\/www.callingithome.com\/\" target=\"_blank\" rel=\"noopener\">Calling it Home<\/a>, j'ai d\u00e9cid\u00e9 de donner \u00e0 ma salle de bricolage\u00a0une\u00a0mise-\u00e0-jour. Ou plus pr\u00e9cis\u00e9ment, je\u00a0veux\u00a0faire\u00a0une salle de bricolage digne de ce nom! Vous pouvez voir le r\u00e9capitulatif\u00a0ici :<\/p>\n<p><a href=\"https:\/\/nelidesign.com\/one-room-challenge-craft-room-week-1\/\" target=\"_blank\" rel=\"noopener\">Semaine 1<\/a>\u00a0|<a href=\"https:\/\/nelidesign.com\/upgrade-of-an-ordinary-shelf-unit-with-old-book-pages-orc-week-2\/\" target=\"_blank\" rel=\"noopener\">\u00a0Semaine 2<\/a>\u00a0|\u00a0<a href=\"https:\/\/nelidesign.com\/craft-room-makeover-one-room-challenge-week-3\/\" target=\"_blank\" rel=\"noopener\">Semaine 3<\/a>\u00a0| <a href=\"https:\/\/nelidesign.com\/wine-crates-floating-shelves-one-room-challenge-week-4\/\" target=\"_blank\" rel=\"noopener\">Semaine 4<\/a> | Semaine 5 | <a href=\"https:\/\/nelidesign.com\/fr\/devoilement-salle-de-bricolage-one-room-challenge-semaine-6\/\">Semaine 6<\/a><\/p>\n<p><a href=\"http:\/\/www.callingithome.com\/blog\/2017\/5\/one-room-challenge-guest-participants-week-5\"><img class=\"aligncenter\" title=\"\" alt=\"Hide a pipe | pegboard in craftroom | how to hang a pegboard | DIY | Hooks on pegboards\" border=\"0\" \/><\/a><\/p>\n<h2>Comment install\u00e9 le panneau trou\u00e9<\/h2>\n<p><i><span style=\"font-weight: 400;\">Cette publication contient des liens vers des produits affili\u00e9s pour votre convenance et sans frais suppl\u00e9mentaires pour vous. <\/span><\/i><a href=\"https:\/\/nelidesign.com\/fr\/divulgation\/\"><i><span style=\"font-weight: 400;\">Cliquez ici pour lire ma politique de divulgation compl\u00e8te.<\/span><\/i><\/a><\/p>\n<p>Ce dont\u00a0vous avez\u00a0besoin :<\/p>\n<p>[wc_box color=\"primary\" text_align=\"left\" margin_top=\"\" margin_bottom=\"\" class=\"\"]<\/p>\n<ul>\n<li>montants 2 x 3<\/li>\n<li>Vis<\/li>\n<li>Ancrages \u00a0muraux<\/li>\n<li>Panneau trou\u00e9<\/li>\n<li><a href=\"https:\/\/www.amazon.com\/s\/ref=as_li_ss_tl?url=search-alias=aps&amp;field-keywords=pegboard+hooks&amp;sprefix=pegboard,aps,209&amp;crid=XLQZNA4K1WRM&amp;rh=i:aps,k:pegboard+hooks&amp;linkCode=ll2&amp;tag=nelidesign20-20&amp;linkId=d57e58c0e8ee41f4a92de4e2d2a53d3e\" target=\"_blank\" rel=\"nofollow noopener\">Crochets et accessoires pour panneau trou\u00e9<\/a><\/li>\n<li><a href=\"https:\/\/www.amazon.com\/s\/ref=as_li_ss_tl?url=search-alias=aps&amp;field-keywords=pegboard+spacers&amp;sprefix=pegspacers,aps,205&amp;crid=JPTM56JPHK9W&amp;linkCode=ll2&amp;tag=nelidesign20-20&amp;linkId=6d28d8f82316c537f7ecc97a76c93211\" target=\"_blank\" rel=\"nofollow noopener\">Espaceur<\/a><\/li>\n<\/ul>\n<p>[\/wc_box]<\/p>\n<p>Premi\u00e8rement, j'ai achet\u00e9 \u00a02- 2 x 3. Ils \u00e9taient de la m\u00eame profondeur\u00a0que le tuyau. Nous avons\u00a0utilis\u00e9 des vis et \u00e9galement des ancrages muraux lorsque les 2 x 3 n'\u00e9taient pas align\u00e9s avec les colombages.<\/p>\n<p><a><img class=\"aligncenter\" alt=\"Hide a pipe | pegboard in craftroom | how to hang a pegboard | DIY | Hooks on pegboards\" width=\"500\" height=\"750\" border=\"0\" \/><\/a><\/p>\n<p><img class=\"alignleft\" title=\"\" alt=\"Hide a pipe | pegboard in craftroom | how to hang a pegboard | DIY | Hooks on pegboards\" width=\"400\" height=\"266\" border=\"0\" \/>Ensuite, nous avons coup\u00e9 le panneau trou\u00e9 de la grandeur requise. Nous avons \u00e9galement utilis\u00e9 des espaceurs\u00a0pour s'assurer que les 2 x 3 ne\u00a0bloquaient aucun trou du panneau.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Une fois\u00a0ceci r\u00e9alis\u00e9, nous avons install\u00e9 de chaque c\u00f4t\u00e9 les deux\u00a0biblioth\u00e8ques<strong> Billy CD\/DVD <\/strong>que\u00a0nous avions\u00a0depuis tr\u00e8s longtemps. \u00a0Mais ces photos seront pour <a href=\"https:\/\/nelidesign.com\/fr\/devoilement-salle-de-bricolage-one-room-challenge-semaine-6\/\" target=\"_blank\" rel=\"noopener\">la semaine prochaine, lors de la r\u00e9v\u00e9lation finale<\/a>!\u00a0\ud83d\ude09<\/p>\n<p>Maintenant, voici un aper\u00e7u du r\u00e9sultat final. Pouvez-vous croire que\u00a0j'ai<strong> beaucoup trop d'espace<\/strong>?<\/p>\n<p><a><img class=\"aligncenter\" title=\"\" alt=\"Hide a pipe | pegboard in craftroom | how to hang a pegboard | DIY | Hooks on pegboards\" border=\"0\" \/><\/a><\/p>\n<p><b>Des suggestions <\/b>sur ce que je pourrais accrocher sur mon nouveau panneau?<\/p>\n<h2>Et S.v.p. \u00e9pinglez si vous ne voulez pas l'oublier!<\/h2>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-3870\" src=\"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Pinterest-pegboard-FR.jpg\" alt=\"Cacher un tuyau dans salle de bricolage avec panneau trou\u00e9 | Hide a pipe | pegboard in craftroom | how to hang a pegboard | DIY | Hooks on pegboards\" width=\"453\" height=\"678\" srcset=\"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Pinterest-pegboard-FR.jpg 735w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Pinterest-pegboard-FR-250x374.jpg 250w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Pinterest-pegboard-FR-550x823.jpg 550w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Pinterest-pegboard-FR-120x180.jpg 120w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Pinterest-pegboard-FR-200x300.jpg 200w, https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Pinterest-pegboard-FR-334x500.jpg 334w\" sizes=\"(max-width: 453px) 100vw, 453px\" \/><\/p>\n<p>[wc_box color=\"secondary\" text_align=\"center\" margin_top=\"\" margin_bottom=\"\" class=\"\"]<\/p>\n<h4 style=\"text-align: center;\">Ne manquez pas les nouvelles gratuit\u00e9s. Inscrivez-vous pour obtenir acc\u00e8s \u00e0 la biblioth\u00e8que remplie de ressources!<\/h4>\n<p style=\"text-align: center;\">[wc_button type=\"warning\" url=\"https:\/\/nelidesign.com\/fr\/landing-page-francais\/\" title=\"Inscrire\" target=\"blank\" url_rel=\"\" icon_left=\"\" icon_right=\"\" position=\"center\" class=\"\"]Je veux m'inscrire![\/wc_button]<\/p>\n<p>[\/wc_box]<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-2946 alignnone\" src=\"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/Signature-2Bnat-1.png\" alt=\"\" width=\"131\" height=\"60\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Pour voir \u00e0 quel \"Link Party\" je participe,<\/span><a href=\"https:\/\/nelidesign.com\/fr\/link-party\/\"> <span style=\"font-weight: 400;\">cliquez ici <\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous souvenez-vous de la premi\u00e8re semaine\u00a0du\u00a0One Room Challenge? Un de mes objectifs \u00e9tait d'installer un panneau trou\u00e9 pour cacher ce tuyau. &nbsp; Eh bien, je l'ai fait (je veux dire, nous l'avons fait parce que je n'aurais pas pu le faire seul! Merci ch\u00e9ri \ud83d\ude0a) Pour le One Room Challenge, de\u00a0Calling it Home, j'ai d\u00e9cid\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"footnotes":""},"categories":[153],"tags":[],"holidays":[],"class_list":["post-5987","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deco","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5 - NeliDesign<\/title>\n<meta name=\"description\" content=\"Voyez comment j&#039;ai cach\u00e9 un tuyau dans ma salle de bricolage \u00e0 l&#039;aide d&#039;un panneau trou\u00e9. J&#039;ai maintenant un \u00e9l\u00e9ment d\u00e9coratif et pratique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5 - NeliDesign\" \/>\n<meta property=\"og:description\" content=\"Voyez comment j&#039;ai cach\u00e9 un tuyau dans ma salle de bricolage \u00e0 l&#039;aide d&#039;un panneau trou\u00e9. J&#039;ai maintenant un \u00e9l\u00e9ment d\u00e9coratif et pratique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/\" \/>\n<meta property=\"og:site_name\" content=\"NeliDesign\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Natalie.NeliDesign\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Natalie.NeliDesign\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-07T21:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-29T17:58:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/peg-2Bboard-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nelidesign\" \/>\n<meta name=\"twitter:site\" content=\"@nelidesign\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/\"},\"author\":{\"name\":\"Natalie\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#\\\/schema\\\/person\\\/0524ce03b052d1c0f41abdf0aa71258e\"},\"headline\":\"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5\",\"datePublished\":\"2017-05-07T21:14:00+00:00\",\"dateModified\":\"2018-09-29T17:58:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/\"},\"wordCount\":410,\"publisher\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#\\\/schema\\\/person\\\/0524ce03b052d1c0f41abdf0aa71258e\"},\"image\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/peg-2Bboard-4.jpg\",\"articleSection\":[\"D\u00e9co\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/\",\"url\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/\",\"name\":\"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5 - NeliDesign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/peg-2Bboard-4.jpg\",\"datePublished\":\"2017-05-07T21:14:00+00:00\",\"dateModified\":\"2018-09-29T17:58:34+00:00\",\"description\":\"Voyez comment j'ai cach\u00e9 un tuyau dans ma salle de bricolage \u00e0 l'aide d'un panneau trou\u00e9. J'ai maintenant un \u00e9l\u00e9ment d\u00e9coratif et pratique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/peg-2Bboard-4.jpg\",\"contentUrl\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/peg-2Bboard-4.jpg\",\"width\":634,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9co\",\"item\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/category\\\/deco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/\",\"name\":\"NeliDesign\",\"description\":\"Cr\u00e9er en toute confiance\",\"publisher\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#\\\/schema\\\/person\\\/0524ce03b052d1c0f41abdf0aa71258e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#\\\/schema\\\/person\\\/0524ce03b052d1c0f41abdf0aa71258e\",\"name\":\"Natalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Natalie2021-1.jpg\",\"url\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Natalie2021-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Natalie2021-1.jpg\",\"width\":350,\"height\":500,\"caption\":\"Natalie\"},\"logo\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Natalie2021-1.jpg\"},\"sameAs\":[\"https:\\\/\\\/nelidesign.com\\\/about-me2\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Natalie.NeliDesign\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Natalie.NeliDesign\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/nelidesign\\\/\",\"https:\\\/\\\/www.youtube.com\\\/nelidesign\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5 - NeliDesign","description":"Voyez comment j'ai cach\u00e9 un tuyau dans ma salle de bricolage \u00e0 l'aide d'un panneau trou\u00e9. J'ai maintenant un \u00e9l\u00e9ment d\u00e9coratif et pratique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5 - NeliDesign","og_description":"Voyez comment j'ai cach\u00e9 un tuyau dans ma salle de bricolage \u00e0 l'aide d'un panneau trou\u00e9. J'ai maintenant un \u00e9l\u00e9ment d\u00e9coratif et pratique.","og_url":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/","og_site_name":"NeliDesign","article_publisher":"https:\/\/www.facebook.com\/Natalie.NeliDesign\/","article_author":"https:\/\/www.facebook.com\/Natalie.NeliDesign\/","article_published_time":"2017-05-07T21:14:00+00:00","article_modified_time":"2018-09-29T17:58:34+00:00","og_image":[{"width":634,"height":750,"url":"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/peg-2Bboard-4.jpg","type":"image\/jpeg"}],"author":"Natalie","twitter_card":"summary_large_image","twitter_creator":"@nelidesign","twitter_site":"@nelidesign","twitter_misc":{"\u00c9crit par":"Natalie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/#article","isPartOf":{"@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/"},"author":{"name":"Natalie","@id":"https:\/\/nelidesign.com\/fr\/#\/schema\/person\/0524ce03b052d1c0f41abdf0aa71258e"},"headline":"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5","datePublished":"2017-05-07T21:14:00+00:00","dateModified":"2018-09-29T17:58:34+00:00","mainEntityOfPage":{"@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/"},"wordCount":410,"publisher":{"@id":"https:\/\/nelidesign.com\/fr\/#\/schema\/person\/0524ce03b052d1c0f41abdf0aa71258e"},"image":{"@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/#primaryimage"},"thumbnailUrl":"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/peg-2Bboard-4.jpg","articleSection":["D\u00e9co"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/","url":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/","name":"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5 - NeliDesign","isPartOf":{"@id":"https:\/\/nelidesign.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/#primaryimage"},"image":{"@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/#primaryimage"},"thumbnailUrl":"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/peg-2Bboard-4.jpg","datePublished":"2017-05-07T21:14:00+00:00","dateModified":"2018-09-29T17:58:34+00:00","description":"Voyez comment j'ai cach\u00e9 un tuyau dans ma salle de bricolage \u00e0 l'aide d'un panneau trou\u00e9. J'ai maintenant un \u00e9l\u00e9ment d\u00e9coratif et pratique.","breadcrumb":{"@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/#primaryimage","url":"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/peg-2Bboard-4.jpg","contentUrl":"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/peg-2Bboard-4.jpg","width":634,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/nelidesign.com\/fr\/comment-cacher-un-tuyau-en-utilisant-un-panneau-troue-one-room-challenge-semaine-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nelidesign.com\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9co","item":"https:\/\/nelidesign.com\/fr\/category\/deco\/"},{"@type":"ListItem","position":3,"name":"Comment cacher un tuyau en utilisant un panneau trou\u00e9 - One Room Challenge Semaine 5"}]},{"@type":"WebSite","@id":"https:\/\/nelidesign.com\/fr\/#website","url":"https:\/\/nelidesign.com\/fr\/","name":"NeliDesign","description":"Cr\u00e9er en toute confiance","publisher":{"@id":"https:\/\/nelidesign.com\/fr\/#\/schema\/person\/0524ce03b052d1c0f41abdf0aa71258e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nelidesign.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/nelidesign.com\/fr\/#\/schema\/person\/0524ce03b052d1c0f41abdf0aa71258e","name":"Natalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nelidesign.com\/wp-content\/uploads\/2021\/10\/Natalie2021-1.jpg","url":"https:\/\/nelidesign.com\/wp-content\/uploads\/2021\/10\/Natalie2021-1.jpg","contentUrl":"https:\/\/nelidesign.com\/wp-content\/uploads\/2021\/10\/Natalie2021-1.jpg","width":350,"height":500,"caption":"Natalie"},"logo":{"@id":"https:\/\/nelidesign.com\/wp-content\/uploads\/2021\/10\/Natalie2021-1.jpg"},"sameAs":["https:\/\/nelidesign.com\/about-me2\/","https:\/\/www.facebook.com\/Natalie.NeliDesign\/","https:\/\/www.instagram.com\/Natalie.NeliDesign\/","https:\/\/www.pinterest.com\/nelidesign\/","https:\/\/www.youtube.com\/nelidesign"]}]}},"featured_image_src":"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/peg-2Bboard-4-600x400.jpg","featured_image_src_square":"https:\/\/nelidesign.com\/wp-content\/uploads\/2017\/05\/peg-2Bboard-4-600x600.jpg","author_info":{"display_name":"Natalie","author_link":"https:\/\/nelidesign.com\/fr\/author\/natalie-desrochers\/"},"_links":{"self":[{"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/posts\/5987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/comments?post=5987"}],"version-history":[{"count":1,"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/posts\/5987\/revisions"}],"predecessor-version":[{"id":8948,"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/posts\/5987\/revisions\/8948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/media\/6176"}],"wp:attachment":[{"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/media?parent=5987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/categories?post=5987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/tags?post=5987"},{"taxonomy":"holidays","embeddable":true,"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/holidays?post=5987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}} 