{"id":150,"count":86,"description":"","link":"https:\/\/nelidesign.com\/fr\/category\/bricolage\/","name":"Bricolage","slug":"bricolage","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bricolage Archives - NeliDesign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nelidesign.com\/fr\/category\/bricolage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bricolage Archives - NeliDesign\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nelidesign.com\/fr\/category\/bricolage\/\" \/>\n<meta property=\"og:site_name\" content=\"NeliDesign\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nelidesign.com\/wp-content\/uploads\/2020\/11\/Neli-Design-Yoast-FB-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nelidesign\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/category\\\/bricolage\\\/\",\"url\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/category\\\/bricolage\\\/\",\"name\":\"Bricolage Archives - NeliDesign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/category\\\/bricolage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/category\\\/bricolage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bricolage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/\",\"name\":\"NeliDesign\",\"description\":\"Cr\u00e9er en toute confiance\",\"publisher\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#\\\/schema\\\/person\\\/0524ce03b052d1c0f41abdf0aa71258e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/nelidesign.com\\\/fr\\\/#\\\/schema\\\/person\\\/0524ce03b052d1c0f41abdf0aa71258e\",\"name\":\"Natalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Natalie2021-1.jpg\",\"url\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Natalie2021-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Natalie2021-1.jpg\",\"width\":350,\"height\":500,\"caption\":\"Natalie\"},\"logo\":{\"@id\":\"https:\\\/\\\/nelidesign.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Natalie2021-1.jpg\"},\"sameAs\":[\"https:\\\/\\\/nelidesign.com\\\/about-me2\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Natalie.NeliDesign\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Natalie.NeliDesign\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/nelidesign\\\/\",\"https:\\\/\\\/www.youtube.com\\\/nelidesign\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bricolage Archives - NeliDesign","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nelidesign.com\/fr\/category\/bricolage\/","og_locale":"fr_FR","og_type":"article","og_title":"Bricolage Archives - NeliDesign","og_url":"https:\/\/nelidesign.com\/fr\/category\/bricolage\/","og_site_name":"NeliDesign","og_image":[{"width":1200,"height":630,"url":"https:\/\/nelidesign.com\/wp-content\/uploads\/2020\/11\/Neli-Design-Yoast-FB-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@nelidesign","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nelidesign.com\/fr\/category\/bricolage\/","url":"https:\/\/nelidesign.com\/fr\/category\/bricolage\/","name":"Bricolage Archives - NeliDesign","isPartOf":{"@id":"https:\/\/nelidesign.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/nelidesign.com\/fr\/category\/bricolage\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/nelidesign.com\/fr\/category\/bricolage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nelidesign.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Bricolage"}]},{"@type":"WebSite","@id":"https:\/\/nelidesign.com\/fr\/#website","url":"https:\/\/nelidesign.com\/fr\/","name":"NeliDesign","description":"Cr\u00e9er en toute confiance","publisher":{"@id":"https:\/\/nelidesign.com\/fr\/#\/schema\/person\/0524ce03b052d1c0f41abdf0aa71258e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nelidesign.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/nelidesign.com\/fr\/#\/schema\/person\/0524ce03b052d1c0f41abdf0aa71258e","name":"Natalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nelidesign.com\/wp-content\/uploads\/2021\/10\/Natalie2021-1.jpg","url":"https:\/\/nelidesign.com\/wp-content\/uploads\/2021\/10\/Natalie2021-1.jpg","contentUrl":"https:\/\/nelidesign.com\/wp-content\/uploads\/2021\/10\/Natalie2021-1.jpg","width":350,"height":500,"caption":"Natalie"},"logo":{"@id":"https:\/\/nelidesign.com\/wp-content\/uploads\/2021\/10\/Natalie2021-1.jpg"},"sameAs":["https:\/\/nelidesign.com\/about-me2\/","https:\/\/www.facebook.com\/Natalie.NeliDesign\/","https:\/\/www.instagram.com\/Natalie.NeliDesign\/","https:\/\/www.pinterest.com\/nelidesign\/","https:\/\/www.youtube.com\/nelidesign"]}]}},"_links":{"self":[{"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/categories\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/nelidesign.com\/fr\/wp-json\/wp\/v2\/posts?categories=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}